{"id":175,"count":28,"description":"","link":"https:\/\/usmtwt.com\/en\/product-category\/g508-gmc\/frein-g508-gmc\/","name":"&gt; Brake","slug":"frein-g508-gmc","taxonomy":"product_cat","parent":48,"meta":[],"menu_order":116,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&gt; Brake -<\/title>\n<meta name=\"description\" content=\"Catalogue des pi\u00e8ces d\u00e9tach\u00e9es d&#039;origines de qualit\u00e9 Neuve de Stock \/ New Old Stock pour : G508 GMC CCKW 352, CCKW353, AFKWX\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/usmtwt.com\/product-category\/g508-gmc\/frein-g508-gmc\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&gt; Brake -\" \/>\n<meta property=\"og:description\" content=\"Catalogue des pi\u00e8ces d\u00e9tach\u00e9es d&#039;origines de qualit\u00e9 Neuve de Stock \/ New Old Stock pour : G508 GMC CCKW 352, CCKW353, AFKWX\" \/>\n<meta property=\"og:url\" content=\"https:\/\/usmtwt.com\/product-category\/g508-gmc\/frein-g508-gmc\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/usmtwt.com\\\/product-category\\\/g508-gmc\\\/frein-g508-gmc\\\/\",\"url\":\"https:\\\/\\\/usmtwt.com\\\/product-category\\\/g508-gmc\\\/frein-g508-gmc\\\/\",\"name\":\"&gt; Brake -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/usmtwt.com\\\/#website\"},\"description\":\"Catalogue des pi\u00e8ces d\u00e9tach\u00e9es d'origines de qualit\u00e9 Neuve de Stock \\\/ New Old Stock pour : G508 GMC CCKW 352, CCKW353, AFKWX\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/usmtwt.com\\\/product-category\\\/g508-gmc\\\/frein-g508-gmc\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/usmtwt.com\\\/product-category\\\/g508-gmc\\\/frein-g508-gmc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/usmtwt.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G508 GMC\",\"item\":\"https:\\\/\\\/usmtwt.com\\\/product-category\\\/g508-gmc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"[:fr]&gt; Frein[:en]&gt; Brake[:]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/usmtwt.com\\\/#website\",\"url\":\"https:\\\/\\\/usmtwt.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/usmtwt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"&gt; Brake -","description":"Catalogue des pi\u00e8ces d\u00e9tach\u00e9es d'origines de qualit\u00e9 Neuve de Stock \/ New Old Stock pour : G508 GMC CCKW 352, CCKW353, AFKWX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/usmtwt.com\/product-category\/g508-gmc\/frein-g508-gmc\/","og_locale":"en_US","og_type":"article","og_title":"&gt; Brake -","og_description":"Catalogue des pi\u00e8ces d\u00e9tach\u00e9es d'origines de qualit\u00e9 Neuve de Stock \/ New Old Stock pour : G508 GMC CCKW 352, CCKW353, AFKWX","og_url":"https:\/\/usmtwt.com\/product-category\/g508-gmc\/frein-g508-gmc\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/usmtwt.com\/product-category\/g508-gmc\/frein-g508-gmc\/","url":"https:\/\/usmtwt.com\/product-category\/g508-gmc\/frein-g508-gmc\/","name":"&gt; Brake -","isPartOf":{"@id":"https:\/\/usmtwt.com\/#website"},"description":"Catalogue des pi\u00e8ces d\u00e9tach\u00e9es d'origines de qualit\u00e9 Neuve de Stock \/ New Old Stock pour : G508 GMC CCKW 352, CCKW353, AFKWX","breadcrumb":{"@id":"https:\/\/usmtwt.com\/product-category\/g508-gmc\/frein-g508-gmc\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/usmtwt.com\/product-category\/g508-gmc\/frein-g508-gmc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/usmtwt.com\/"},{"@type":"ListItem","position":2,"name":"G508 GMC","item":"https:\/\/usmtwt.com\/product-category\/g508-gmc\/"},{"@type":"ListItem","position":3,"name":"[:fr]&gt; Frein[:en]&gt; Brake[:]"}]},{"@type":"WebSite","@id":"https:\/\/usmtwt.com\/#website","url":"https:\/\/usmtwt.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/usmtwt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/usmtwt.com\/en\/wp-json\/wp\/v2\/product_cat\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usmtwt.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/usmtwt.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/usmtwt.com\/en\/wp-json\/wp\/v2\/product_cat\/48"}],"wp:post_type":[{"href":"https:\/\/usmtwt.com\/en\/wp-json\/wp\/v2\/product?product_cat=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}